{"id":5908,"date":"2021-10-27T08:42:34","date_gmt":"2021-10-27T06:42:34","guid":{"rendered":"https:\/\/svenskahundklubben.se\/sodertalje\/?post_type=tribe_events&#038;p=5908"},"modified":"2021-10-27T09:38:35","modified_gmt":"2021-10-27T07:38:35","slug":"hundtest","status":"publish","type":"tribe_events","link":"https:\/\/svenskahundklubben.se\/sodertalje\/event\/hundtest\/","title":{"rendered":"Hundtest"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":0,"template":"","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":"","_links_to":"","_links_to_target":""},"tags":[],"tribe_events_cat":[],"class_list":["post-5908","tribe_events","type-tribe_events","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Hundtest - Svenska Hundklubben - S\u00f6dert\u00e4lje<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/svenskahundklubben.se\/sodertalje\/event\/hundtest\/\" \/>\n<meta property=\"og:locale\" content=\"sv_SE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hundtest - Svenska Hundklubben - S\u00f6dert\u00e4lje\" \/>\n<meta property=\"og:url\" content=\"https:\/\/svenskahundklubben.se\/sodertalje\/event\/hundtest\/\" \/>\n<meta property=\"og:site_name\" content=\"Svenska Hundklubben - S\u00f6dert\u00e4lje\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-27T07:38:35+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/svenskahundklubben.se\/sodertalje\/event\/hundtest\/\",\"url\":\"https:\/\/svenskahundklubben.se\/sodertalje\/event\/hundtest\/\",\"name\":\"Hundtest - Svenska Hundklubben - S\u00f6dert\u00e4lje\",\"isPartOf\":{\"@id\":\"https:\/\/svenskahundklubben.se\/sodertalje\/#website\"},\"datePublished\":\"2021-10-27T06:42:34+00:00\",\"dateModified\":\"2021-10-27T07:38:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/svenskahundklubben.se\/sodertalje\/event\/hundtest\/#breadcrumb\"},\"inLanguage\":\"sv-SE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/svenskahundklubben.se\/sodertalje\/event\/hundtest\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/svenskahundklubben.se\/sodertalje\/event\/hundtest\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hem\",\"item\":\"https:\/\/svenskahundklubben.se\/sodertalje\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Evenemang\",\"item\":\"https:\/\/svenskahundklubben.se\/sodertalje\/kalender\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Hundtest\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/svenskahundklubben.se\/sodertalje\/#website\",\"url\":\"https:\/\/svenskahundklubben.se\/sodertalje\/\",\"name\":\"Svenska Hundklubben - S\u00f6dert\u00e4lje\",\"description\":\"Svenska Hundklubben-webbplats\",\"publisher\":{\"@id\":\"https:\/\/svenskahundklubben.se\/sodertalje\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/svenskahundklubben.se\/sodertalje\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sv-SE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/svenskahundklubben.se\/sodertalje\/#organization\",\"name\":\"Svenska Hundklubben - S\u00f6dert\u00e4lje\",\"url\":\"https:\/\/svenskahundklubben.se\/sodertalje\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sv-SE\",\"@id\":\"https:\/\/svenskahundklubben.se\/sodertalje\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/svenskahundklubben.se\/sodertalje\/wp-content\/uploads\/sites\/4\/2019\/08\/SHK-S\u00d6DERT\u00c4LJE-HEADERLOGO.png\",\"contentUrl\":\"https:\/\/svenskahundklubben.se\/sodertalje\/wp-content\/uploads\/sites\/4\/2019\/08\/SHK-S\u00d6DERT\u00c4LJE-HEADERLOGO.png\",\"width\":1200,\"height\":300,\"caption\":\"Svenska Hundklubben - S\u00f6dert\u00e4lje\"},\"image\":{\"@id\":\"https:\/\/svenskahundklubben.se\/sodertalje\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hundtest - Svenska Hundklubben - S\u00f6dert\u00e4lje","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/svenskahundklubben.se\/sodertalje\/event\/hundtest\/","og_locale":"sv_SE","og_type":"article","og_title":"Hundtest - Svenska Hundklubben - S\u00f6dert\u00e4lje","og_url":"https:\/\/svenskahundklubben.se\/sodertalje\/event\/hundtest\/","og_site_name":"Svenska Hundklubben - S\u00f6dert\u00e4lje","article_modified_time":"2021-10-27T07:38:35+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/svenskahundklubben.se\/sodertalje\/event\/hundtest\/","url":"https:\/\/svenskahundklubben.se\/sodertalje\/event\/hundtest\/","name":"Hundtest - Svenska Hundklubben - S\u00f6dert\u00e4lje","isPartOf":{"@id":"https:\/\/svenskahundklubben.se\/sodertalje\/#website"},"datePublished":"2021-10-27T06:42:34+00:00","dateModified":"2021-10-27T07:38:35+00:00","breadcrumb":{"@id":"https:\/\/svenskahundklubben.se\/sodertalje\/event\/hundtest\/#breadcrumb"},"inLanguage":"sv-SE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/svenskahundklubben.se\/sodertalje\/event\/hundtest\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/svenskahundklubben.se\/sodertalje\/event\/hundtest\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hem","item":"https:\/\/svenskahundklubben.se\/sodertalje\/"},{"@type":"ListItem","position":2,"name":"Evenemang","item":"https:\/\/svenskahundklubben.se\/sodertalje\/kalender\/"},{"@type":"ListItem","position":3,"name":"Hundtest"}]},{"@type":"WebSite","@id":"https:\/\/svenskahundklubben.se\/sodertalje\/#website","url":"https:\/\/svenskahundklubben.se\/sodertalje\/","name":"Svenska Hundklubben - S\u00f6dert\u00e4lje","description":"Svenska Hundklubben-webbplats","publisher":{"@id":"https:\/\/svenskahundklubben.se\/sodertalje\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/svenskahundklubben.se\/sodertalje\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sv-SE"},{"@type":"Organization","@id":"https:\/\/svenskahundklubben.se\/sodertalje\/#organization","name":"Svenska Hundklubben - S\u00f6dert\u00e4lje","url":"https:\/\/svenskahundklubben.se\/sodertalje\/","logo":{"@type":"ImageObject","inLanguage":"sv-SE","@id":"https:\/\/svenskahundklubben.se\/sodertalje\/#\/schema\/logo\/image\/","url":"https:\/\/svenskahundklubben.se\/sodertalje\/wp-content\/uploads\/sites\/4\/2019\/08\/SHK-S\u00d6DERT\u00c4LJE-HEADERLOGO.png","contentUrl":"https:\/\/svenskahundklubben.se\/sodertalje\/wp-content\/uploads\/sites\/4\/2019\/08\/SHK-S\u00d6DERT\u00c4LJE-HEADERLOGO.png","width":1200,"height":300,"caption":"Svenska Hundklubben - S\u00f6dert\u00e4lje"},"image":{"@id":"https:\/\/svenskahundklubben.se\/sodertalje\/#\/schema\/logo\/image\/"}}]}},"ticketed":false,"_links":{"self":[{"href":"https:\/\/svenskahundklubben.se\/sodertalje\/wp-json\/wp\/v2\/tribe_events\/5908"}],"collection":[{"href":"https:\/\/svenskahundklubben.se\/sodertalje\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/svenskahundklubben.se\/sodertalje\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/svenskahundklubben.se\/sodertalje\/wp-json\/wp\/v2\/users\/5"}],"version-history":[{"count":1,"href":"https:\/\/svenskahundklubben.se\/sodertalje\/wp-json\/wp\/v2\/tribe_events\/5908\/revisions"}],"predecessor-version":[{"id":5909,"href":"https:\/\/svenskahundklubben.se\/sodertalje\/wp-json\/wp\/v2\/tribe_events\/5908\/revisions\/5909"}],"wp:attachment":[{"href":"https:\/\/svenskahundklubben.se\/sodertalje\/wp-json\/wp\/v2\/media?parent=5908"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/svenskahundklubben.se\/sodertalje\/wp-json\/wp\/v2\/tags?post=5908"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/svenskahundklubben.se\/sodertalje\/wp-json\/wp\/v2\/tribe_events_cat?post=5908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}